{"id":18056,"date":"2026-05-07T19:54:45","date_gmt":"2026-05-07T18:54:45","guid":{"rendered":"https:\/\/www.mixedabilitysports.org\/?p=18056"},"modified":"2026-05-07T19:54:45","modified_gmt":"2026-05-07T18:54:45","slug":"el-espiritu-del-rugby-mixed-ability-tendra-su-reconocimiento-en-el-i-smart-granada-2026","status":"publish","type":"post","link":"https:\/\/www.mixedabilitysports.org\/es\/el-espiritu-del-rugby-mixed-ability-tendra-su-reconocimiento-en-el-i-smart-granada-2026\/","title":{"rendered":"El Esp\u00edritu del Rugby Mixed Ability Tendr\u00e1 su Reconocimiento en el I SMART Granada 2026"},"content":{"rendered":"<h4>El Trofeo del Esp\u00edritu del Rugby Mixed Ability ser\u00e1 uno de los reconocimientos m\u00e1s significativos que se pondr\u00e1n en juego durante el 1er Campeonato Nacional de Rugby Mixed Ability \u201cSMART Granada 2026\u201d organizado por el C.D. Rugby Escoriones con el apoyo de IMAS Espa\u00f1a.<\/h4>\n<p>&nbsp;<\/p>\n<p>Este galard\u00f3n nace con el prop\u00f3sito de destacar, entre todos los equipos participantes, aquellos que mejor representen los valores esenciales de este movimiento: la inclusi\u00f3n real, la igualdad de oportunidades, el compa\u00f1erismo y el profundo sentido de pertenencia que caracteriza al rugby Mixed Ability.<\/p>\n<p>M\u00e1s all\u00e1 de los resultados deportivos, este trofeo pone el foco en la esencia del juego como herramienta de transformaci\u00f3n social, reconociendo actitudes, comportamientos y din\u00e1micas de equipo que reflejen el esp\u00edritu integrador que impulsa esta modalidad.<\/p>\n<p>Este reconocimiento contin\u00faa la tradici\u00f3n de los Trofeos Esp\u00edritu del Mixed Ability, presentes tambi\u00e9n en grandes eventos internacionales del movimiento, como los mundiales IMART (Bradford 2015, Vitoria-Gasteiz 2017, Cork 2022 y Pamplona 2025) y las Regatas Internacionales Mixed Ability, celebradas en Cork, Irlanda (2022), y en Orio, Espa\u00f1a (2025). De esta manera, SMART Granada 2026 se suma a una trayectoria de eventos internacionales que promueven, visibilizan y reconocen los valores fundamentales del deporte Mixed Ability.<\/p>\n<p>El trofeo ha sido confeccionado por la Escuela de Arte y Superior de Dise\u00f1o de Pamplona, bajo la autor\u00eda de la docente Zuri\u00f1e Urbeltz Yaben, a quien agradecemos especialmente su implicaci\u00f3n y sensibilidad para plasmar en una pieza tangible los valores que este reconocimiento representa. Confiamos en que esta colaboraci\u00f3n sea el inicio de futuros proyectos conjuntos que sigan fortaleciendo los v\u00ednculos entre el deporte, el arte y la inclusi\u00f3n social.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18060 \" src=\"https:\/\/www.mixedabilitysports.org\/wp-content\/uploads\/1777289589929-1024x965.jpg\" alt=\"\" width=\"712\" height=\"671\" \/><\/p>\n<p>Asimismo, esta iniciativa se alinea con diversos Objetivos de Desarrollo Sostenible (ODS), especialmente el ODS 10 (Reducci\u00f3n de las desigualdades), el ODS 17 (Alianzas para lograr los objetivos) y el ODS 4 (Educaci\u00f3n de calidad), promoviendo sinergias basadas en el trabajo colaborativo, la generaci\u00f3n de redes y la formalizaci\u00f3n de convenios de cooperaci\u00f3n que potencien el impacto social del deporte Mixed Ability.<\/p>\n<p>El Trofeo del Esp\u00edritu del Rugby Mixed Ability no solo premiar\u00e1 a un equipo, sino que simbolizar\u00e1 el compromiso colectivo con un modelo de deporte m\u00e1s justo, accesible y humano.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18063 \" src=\"https:\/\/www.mixedabilitysports.org\/wp-content\/uploads\/Diseno-sin-titulo-1-2-768x1024.jpg\" alt=\"\" width=\"476\" height=\"635\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Trofeo del Esp\u00edritu del Rugby Mixed Ability ser\u00e1 uno de los reconocimientos m\u00e1s significativos que se pondr\u00e1n en juego durante el 1er Campeonato Nacional de Rugby Mixed Ability \u201cSMART Granada 2026\u201d organizado por el C.D. Rugby Escoriones con el apoyo de IMAS Espa\u00f1a. &nbsp; Este galard\u00f3n nace con el prop\u00f3sito de destacar, entre todos [&hellip;]<\/p>\n","protected":false},"author":938,"featured_media":18070,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[549],"tags":[1563,1565,1566,247,1536,1352,374,511,1562,390,1577],"class_list":["post-18056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","tag-1er-torneo-rugby-mixed-ability-espana","tag-escoriones-de-granada","tag-escoriones-rugby-club-de-granada","tag-imas-es","tag-imas-espana","tag-imas-spain-es","tag-international-mixed-ability-sports-es","tag-mixed-ability-sports-es","tag-smart-granada-2026","tag-spirit-of-mixed-ability-rugby-trophy-es","tag-trofeo-espiritu-del-mixed-ability"],"_links":{"self":[{"href":"https:\/\/www.mixedabilitysports.org\/es\/wp-json\/wp\/v2\/posts\/18056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mixedabilitysports.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mixedabilitysports.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mixedabilitysports.org\/es\/wp-json\/wp\/v2\/users\/938"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mixedabilitysports.org\/es\/wp-json\/wp\/v2\/comments?post=18056"}],"version-history":[{"count":3,"href":"https:\/\/www.mixedabilitysports.org\/es\/wp-json\/wp\/v2\/posts\/18056\/revisions"}],"predecessor-version":[{"id":18074,"href":"https:\/\/www.mixedabilitysports.org\/es\/wp-json\/wp\/v2\/posts\/18056\/revisions\/18074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mixedabilitysports.org\/es\/wp-json\/wp\/v2\/media\/18070"}],"wp:attachment":[{"href":"https:\/\/www.mixedabilitysports.org\/es\/wp-json\/wp\/v2\/media?parent=18056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mixedabilitysports.org\/es\/wp-json\/wp\/v2\/categories?post=18056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mixedabilitysports.org\/es\/wp-json\/wp\/v2\/tags?post=18056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}